{"id":3158,"date":"2017-09-12T14:08:03","date_gmt":"2017-09-12T12:08:03","guid":{"rendered":"http:\/\/www.holstein.ch\/?p=3158"},"modified":"2019-06-21T14:30:20","modified_gmt":"2019-06-21T12:30:20","slug":"die-besten-leistungen-august-2017","status":"publish","type":"post","link":"https:\/\/www.holstein.ch\/de\/die-besten-leistungen-august-2017\/","title":{"rendered":"Die besten Leistungen &#8211; August 2017"},"content":{"rendered":"<p>\t\t\t\tEs ist immer motivierend, sich mit anderen vergleichen zu k\u00f6nnen. Um diesem Wunsch gerecht zu werden hat Holstein Switzerland dieses System der monatlichen Statistiken mit den besten Holstein Leistungen des Monates in folgenden Bereichen entwickelt:<\/p>\n<ul>\n<li>Stiereneinsatz<\/li>\n<li>Lineare Beschreibung<\/li>\n<li>Milchkontrolle<\/li>\n<li>Herdebuch (registrierte Auszeichnungen)<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Es ist immer motivierend, sich mit anderen vergleichen zu k\u00f6nnen. Um diesem Wunsch gerecht zu werden hat Holstein Switzerland dieses System der monatlichen Statistiken mit den besten Holstein Leistungen des Monates in folgenden Bereichen entwickelt: Stiereneinsatz Lineare Beschreibung Milchkontrolle Herdebuch (registrierte Auszeichnungen)<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[37],"tags":[],"class_list":["post-3158","post","type-post","status-publish","format-standard","hentry","category-statistiken"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die besten Leistungen - August 2017 - Holstein Switzerland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.holstein.ch\/de\/die-besten-leistungen-august-2017\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die besten Leistungen - August 2017 - Holstein Switzerland\" \/>\n<meta property=\"og:description\" content=\"Es ist immer motivierend, sich mit anderen vergleichen zu k\u00f6nnen. Um diesem Wunsch gerecht zu werden hat Holstein Switzerland dieses System der monatlichen Statistiken mit den besten Holstein Leistungen des Monates in folgenden Bereichen entwickelt: Stiereneinsatz Lineare Beschreibung Milchkontrolle Herdebuch (registrierte Auszeichnungen)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.holstein.ch\/de\/die-besten-leistungen-august-2017\/\" \/>\n<meta property=\"og:site_name\" content=\"Holstein Switzerland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HolSwi\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-12T12:08:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-21T12:30:20+00:00\" \/>\n<meta name=\"author\" content=\"Tissier PIerre-Ollivier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tissier PIerre-Ollivier\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/die-besten-leistungen-august-2017\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/die-besten-leistungen-august-2017\\\/\"},\"author\":{\"name\":\"Tissier PIerre-Ollivier\",\"@id\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/#\\\/schema\\\/person\\\/b543128beebcdb398aa998aa7bd24f33\"},\"headline\":\"Die besten Leistungen &#8211; August 2017\",\"datePublished\":\"2017-09-12T12:08:03+00:00\",\"dateModified\":\"2019-06-21T12:30:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/die-besten-leistungen-august-2017\\\/\"},\"wordCount\":48,\"publisher\":{\"@id\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/#organization\"},\"articleSection\":[\"Statistiken\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/die-besten-leistungen-august-2017\\\/\",\"url\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/die-besten-leistungen-august-2017\\\/\",\"name\":\"Die besten Leistungen - August 2017 - Holstein Switzerland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/#website\"},\"datePublished\":\"2017-09-12T12:08:03+00:00\",\"dateModified\":\"2019-06-21T12:30:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/die-besten-leistungen-august-2017\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.holstein.ch\\\/de\\\/die-besten-leistungen-august-2017\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/die-besten-leistungen-august-2017\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Statistiken\",\"item\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/publikationen\\\/statistiken\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die besten Leistungen &#8211; August 2017\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/\",\"name\":\"Holstein Switzerland\",\"description\":\"Holstein Switzerland\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/#organization\",\"name\":\"Holstein Switzerland\",\"url\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.holstein.ch\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/holstein_switzerland_logo.png\",\"contentUrl\":\"https:\\\/\\\/www.holstein.ch\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/holstein_switzerland_logo.png\",\"width\":800,\"height\":621,\"caption\":\"Holstein Switzerland\"},\"image\":{\"@id\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/HolSwi\",\"https:\\\/\\\/www.youtube.com\\\/@holsteinswitzerland\",\"https:\\\/\\\/www.instagram.com\\\/holstein_switzerland\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/#\\\/schema\\\/person\\\/b543128beebcdb398aa998aa7bd24f33\",\"name\":\"Tissier PIerre-Ollivier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bd7860641a9a141305b15dcc1a9a9fe7685a2cd6846c324653d1f4f38f4f8e7e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bd7860641a9a141305b15dcc1a9a9fe7685a2cd6846c324653d1f4f38f4f8e7e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bd7860641a9a141305b15dcc1a9a9fe7685a2cd6846c324653d1f4f38f4f8e7e?s=96&d=mm&r=g\",\"caption\":\"Tissier PIerre-Ollivier\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die besten Leistungen - August 2017 - Holstein Switzerland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.holstein.ch\/de\/die-besten-leistungen-august-2017\/","og_locale":"de_DE","og_type":"article","og_title":"Die besten Leistungen - August 2017 - Holstein Switzerland","og_description":"Es ist immer motivierend, sich mit anderen vergleichen zu k\u00f6nnen. Um diesem Wunsch gerecht zu werden hat Holstein Switzerland dieses System der monatlichen Statistiken mit den besten Holstein Leistungen des Monates in folgenden Bereichen entwickelt: Stiereneinsatz Lineare Beschreibung Milchkontrolle Herdebuch (registrierte Auszeichnungen)","og_url":"https:\/\/www.holstein.ch\/de\/die-besten-leistungen-august-2017\/","og_site_name":"Holstein Switzerland","article_publisher":"https:\/\/www.facebook.com\/HolSwi","article_published_time":"2017-09-12T12:08:03+00:00","article_modified_time":"2019-06-21T12:30:20+00:00","author":"Tissier PIerre-Ollivier","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Tissier PIerre-Ollivier"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.holstein.ch\/de\/die-besten-leistungen-august-2017\/#article","isPartOf":{"@id":"https:\/\/www.holstein.ch\/de\/die-besten-leistungen-august-2017\/"},"author":{"name":"Tissier PIerre-Ollivier","@id":"https:\/\/www.holstein.ch\/de\/#\/schema\/person\/b543128beebcdb398aa998aa7bd24f33"},"headline":"Die besten Leistungen &#8211; August 2017","datePublished":"2017-09-12T12:08:03+00:00","dateModified":"2019-06-21T12:30:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.holstein.ch\/de\/die-besten-leistungen-august-2017\/"},"wordCount":48,"publisher":{"@id":"https:\/\/www.holstein.ch\/de\/#organization"},"articleSection":["Statistiken"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.holstein.ch\/de\/die-besten-leistungen-august-2017\/","url":"https:\/\/www.holstein.ch\/de\/die-besten-leistungen-august-2017\/","name":"Die besten Leistungen - August 2017 - Holstein Switzerland","isPartOf":{"@id":"https:\/\/www.holstein.ch\/de\/#website"},"datePublished":"2017-09-12T12:08:03+00:00","dateModified":"2019-06-21T12:30:20+00:00","breadcrumb":{"@id":"https:\/\/www.holstein.ch\/de\/die-besten-leistungen-august-2017\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.holstein.ch\/de\/die-besten-leistungen-august-2017\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.holstein.ch\/de\/die-besten-leistungen-august-2017\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Statistiken","item":"https:\/\/www.holstein.ch\/de\/publikationen\/statistiken\/"},{"@type":"ListItem","position":2,"name":"Die besten Leistungen &#8211; August 2017"}]},{"@type":"WebSite","@id":"https:\/\/www.holstein.ch\/de\/#website","url":"https:\/\/www.holstein.ch\/de\/","name":"Holstein Switzerland","description":"Holstein Switzerland","publisher":{"@id":"https:\/\/www.holstein.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.holstein.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.holstein.ch\/de\/#organization","name":"Holstein Switzerland","url":"https:\/\/www.holstein.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.holstein.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.holstein.ch\/wp-content\/uploads\/2023\/09\/holstein_switzerland_logo.png","contentUrl":"https:\/\/www.holstein.ch\/wp-content\/uploads\/2023\/09\/holstein_switzerland_logo.png","width":800,"height":621,"caption":"Holstein Switzerland"},"image":{"@id":"https:\/\/www.holstein.ch\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/HolSwi","https:\/\/www.youtube.com\/@holsteinswitzerland","https:\/\/www.instagram.com\/holstein_switzerland"]},{"@type":"Person","@id":"https:\/\/www.holstein.ch\/de\/#\/schema\/person\/b543128beebcdb398aa998aa7bd24f33","name":"Tissier PIerre-Ollivier","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/bd7860641a9a141305b15dcc1a9a9fe7685a2cd6846c324653d1f4f38f4f8e7e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bd7860641a9a141305b15dcc1a9a9fe7685a2cd6846c324653d1f4f38f4f8e7e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bd7860641a9a141305b15dcc1a9a9fe7685a2cd6846c324653d1f4f38f4f8e7e?s=96&d=mm&r=g","caption":"Tissier PIerre-Ollivier"}}]}},"_links":{"self":[{"href":"https:\/\/www.holstein.ch\/de\/wp-json\/wp\/v2\/posts\/3158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.holstein.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.holstein.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.holstein.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.holstein.ch\/de\/wp-json\/wp\/v2\/comments?post=3158"}],"version-history":[{"count":0,"href":"https:\/\/www.holstein.ch\/de\/wp-json\/wp\/v2\/posts\/3158\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.holstein.ch\/de\/wp-json\/wp\/v2\/media?parent=3158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.holstein.ch\/de\/wp-json\/wp\/v2\/categories?post=3158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.holstein.ch\/de\/wp-json\/wp\/v2\/tags?post=3158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}