{"id":35859,"date":"2026-01-09T10:00:00","date_gmt":"2026-01-09T09:00:00","guid":{"rendered":"https:\/\/www.holstein.ch\/?p=35859"},"modified":"2026-01-07T11:49:13","modified_gmt":"2026-01-07T10:49:13","slug":"die-besten-leistungen-dezember-2025","status":"publish","type":"post","link":"https:\/\/www.holstein.ch\/de\/die-besten-leistungen-dezember-2025\/","title":{"rendered":"Die Besten Leistungen \u2013 Dezember 2025"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Knonaudale&nbsp;Goldwyn AMY<\/strong>&nbsp;von Villiger Reto, in Auw (AG) wurde im Dezember mit ihrem siebten Stern ausgezeichnet. Neben ihrer Vererbungskraft \u00fcberzeugt diese Kuh auch mit einer Lebensleistung \u00fcber vier Laktationen von 79&#8217;469 kg Milch bei Inhaltsstoffen von 4.07% Fett und 3.34% Eiweiss. Bei einer Einstufung von VG 88 wurde sie zudem mit der Goldmedal ausgezeichnet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">AMY ist eine Vollschwester zur kanadischen Zuchtkuh&nbsp;<strong>Knonaudale JASMINE&nbsp;<\/strong>EX 96 4E, welche im Herdebuch von Holstein Kanada mit 18 Sternen ausgezeichnet ist.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Herzliche Gratulation zu diesem Zuchterfolg!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Knonaudale&nbsp;Goldwyn AMY&nbsp;von Villiger Reto, in Auw (AG) wurde im Dezember mit ihrem siebten Stern ausgezeichnet. Neben ihrer Vererbungskraft \u00fcberzeugt diese Kuh auch mit einer Lebensleistung \u00fcber vier Laktationen von 79&#8217;469 kg Milch bei Inhaltsstoffen von 4.07% Fett und 3.34% Eiweiss. Bei einer Einstufung von VG 88 wurde sie zudem mit der Goldmedal ausgezeichnet. AMY ist [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":35852,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[37],"tags":[],"class_list":["post-35859","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-statistiken"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die Besten Leistungen \u2013 Dezember 2025 - Holstein Switzerland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.holstein.ch\/de\/die-besten-leistungen-dezember-2025\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Besten Leistungen \u2013 Dezember 2025 - Holstein Switzerland\" \/>\n<meta property=\"og:description\" content=\"Knonaudale&nbsp;Goldwyn AMY&nbsp;von Villiger Reto, in Auw (AG) wurde im Dezember mit ihrem siebten Stern ausgezeichnet. Neben ihrer Vererbungskraft \u00fcberzeugt diese Kuh auch mit einer Lebensleistung \u00fcber vier Laktationen von 79&#8217;469 kg Milch bei Inhaltsstoffen von 4.07% Fett und 3.34% Eiweiss. Bei einer Einstufung von VG 88 wurde sie zudem mit der Goldmedal ausgezeichnet. AMY ist [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.holstein.ch\/de\/die-besten-leistungen-dezember-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Holstein Switzerland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HolSwi\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-09T09:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.holstein.ch\/wp-content\/uploads\/2026\/01\/00-squareWEB.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1081\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marie-Jos\u00e9 Rossier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marie-Jos\u00e9 Rossier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/die-besten-leistungen-dezember-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/die-besten-leistungen-dezember-2025\\\/\"},\"author\":{\"name\":\"Marie-Jos\u00e9 Rossier\",\"@id\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/#\\\/schema\\\/person\\\/91e83d490a3dfd0906e65d37ecbcbfb6\"},\"headline\":\"Die Besten Leistungen \u2013 Dezember 2025\",\"datePublished\":\"2026-01-09T09:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/die-besten-leistungen-dezember-2025\\\/\"},\"wordCount\":85,\"publisher\":{\"@id\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/die-besten-leistungen-dezember-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.holstein.ch\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/00-squareWEB.jpg\",\"articleSection\":[\"Statistiken\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/die-besten-leistungen-dezember-2025\\\/\",\"url\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/die-besten-leistungen-dezember-2025\\\/\",\"name\":\"Die Besten Leistungen \u2013 Dezember 2025 - Holstein Switzerland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/die-besten-leistungen-dezember-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/die-besten-leistungen-dezember-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.holstein.ch\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/00-squareWEB.jpg\",\"datePublished\":\"2026-01-09T09:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/die-besten-leistungen-dezember-2025\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.holstein.ch\\\/de\\\/die-besten-leistungen-dezember-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/die-besten-leistungen-dezember-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.holstein.ch\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/00-squareWEB.jpg\",\"contentUrl\":\"https:\\\/\\\/www.holstein.ch\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/00-squareWEB.jpg\",\"width\":1080,\"height\":1081},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/die-besten-leistungen-dezember-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Statistiken\",\"item\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/publikationen\\\/statistiken\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Besten Leistungen \u2013 Dezember 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/\",\"name\":\"Holstein Switzerland\",\"description\":\"Holstein Switzerland\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/#organization\",\"name\":\"Holstein Switzerland\",\"url\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.holstein.ch\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/holstein_switzerland_logo.png\",\"contentUrl\":\"https:\\\/\\\/www.holstein.ch\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/holstein_switzerland_logo.png\",\"width\":800,\"height\":621,\"caption\":\"Holstein Switzerland\"},\"image\":{\"@id\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/HolSwi\",\"https:\\\/\\\/www.youtube.com\\\/@holsteinswitzerland\",\"https:\\\/\\\/www.instagram.com\\\/holstein_switzerland\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.holstein.ch\\\/de\\\/#\\\/schema\\\/person\\\/91e83d490a3dfd0906e65d37ecbcbfb6\",\"name\":\"Marie-Jos\u00e9 Rossier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68ae16187ec4e6b8556e0e811e57dcb7c21c138f955e02087102f283ee2b3bb6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68ae16187ec4e6b8556e0e811e57dcb7c21c138f955e02087102f283ee2b3bb6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68ae16187ec4e6b8556e0e811e57dcb7c21c138f955e02087102f283ee2b3bb6?s=96&d=mm&r=g\",\"caption\":\"Marie-Jos\u00e9 Rossier\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die Besten Leistungen \u2013 Dezember 2025 - Holstein Switzerland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.holstein.ch\/de\/die-besten-leistungen-dezember-2025\/","og_locale":"de_DE","og_type":"article","og_title":"Die Besten Leistungen \u2013 Dezember 2025 - Holstein Switzerland","og_description":"Knonaudale&nbsp;Goldwyn AMY&nbsp;von Villiger Reto, in Auw (AG) wurde im Dezember mit ihrem siebten Stern ausgezeichnet. Neben ihrer Vererbungskraft \u00fcberzeugt diese Kuh auch mit einer Lebensleistung \u00fcber vier Laktationen von 79&#8217;469 kg Milch bei Inhaltsstoffen von 4.07% Fett und 3.34% Eiweiss. Bei einer Einstufung von VG 88 wurde sie zudem mit der Goldmedal ausgezeichnet. AMY ist [&hellip;]","og_url":"https:\/\/www.holstein.ch\/de\/die-besten-leistungen-dezember-2025\/","og_site_name":"Holstein Switzerland","article_publisher":"https:\/\/www.facebook.com\/HolSwi","article_published_time":"2026-01-09T09:00:00+00:00","og_image":[{"width":1080,"height":1081,"url":"https:\/\/www.holstein.ch\/wp-content\/uploads\/2026\/01\/00-squareWEB.jpg","type":"image\/jpeg"}],"author":"Marie-Jos\u00e9 Rossier","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Marie-Jos\u00e9 Rossier","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.holstein.ch\/de\/die-besten-leistungen-dezember-2025\/#article","isPartOf":{"@id":"https:\/\/www.holstein.ch\/de\/die-besten-leistungen-dezember-2025\/"},"author":{"name":"Marie-Jos\u00e9 Rossier","@id":"https:\/\/www.holstein.ch\/de\/#\/schema\/person\/91e83d490a3dfd0906e65d37ecbcbfb6"},"headline":"Die Besten Leistungen \u2013 Dezember 2025","datePublished":"2026-01-09T09:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.holstein.ch\/de\/die-besten-leistungen-dezember-2025\/"},"wordCount":85,"publisher":{"@id":"https:\/\/www.holstein.ch\/de\/#organization"},"image":{"@id":"https:\/\/www.holstein.ch\/de\/die-besten-leistungen-dezember-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/www.holstein.ch\/wp-content\/uploads\/2026\/01\/00-squareWEB.jpg","articleSection":["Statistiken"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.holstein.ch\/de\/die-besten-leistungen-dezember-2025\/","url":"https:\/\/www.holstein.ch\/de\/die-besten-leistungen-dezember-2025\/","name":"Die Besten Leistungen \u2013 Dezember 2025 - Holstein Switzerland","isPartOf":{"@id":"https:\/\/www.holstein.ch\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.holstein.ch\/de\/die-besten-leistungen-dezember-2025\/#primaryimage"},"image":{"@id":"https:\/\/www.holstein.ch\/de\/die-besten-leistungen-dezember-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/www.holstein.ch\/wp-content\/uploads\/2026\/01\/00-squareWEB.jpg","datePublished":"2026-01-09T09:00:00+00:00","breadcrumb":{"@id":"https:\/\/www.holstein.ch\/de\/die-besten-leistungen-dezember-2025\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.holstein.ch\/de\/die-besten-leistungen-dezember-2025\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.holstein.ch\/de\/die-besten-leistungen-dezember-2025\/#primaryimage","url":"https:\/\/www.holstein.ch\/wp-content\/uploads\/2026\/01\/00-squareWEB.jpg","contentUrl":"https:\/\/www.holstein.ch\/wp-content\/uploads\/2026\/01\/00-squareWEB.jpg","width":1080,"height":1081},{"@type":"BreadcrumbList","@id":"https:\/\/www.holstein.ch\/de\/die-besten-leistungen-dezember-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Statistiken","item":"https:\/\/www.holstein.ch\/de\/publikationen\/statistiken\/"},{"@type":"ListItem","position":2,"name":"Die Besten Leistungen \u2013 Dezember 2025"}]},{"@type":"WebSite","@id":"https:\/\/www.holstein.ch\/de\/#website","url":"https:\/\/www.holstein.ch\/de\/","name":"Holstein Switzerland","description":"Holstein Switzerland","publisher":{"@id":"https:\/\/www.holstein.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.holstein.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.holstein.ch\/de\/#organization","name":"Holstein Switzerland","url":"https:\/\/www.holstein.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.holstein.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.holstein.ch\/wp-content\/uploads\/2023\/09\/holstein_switzerland_logo.png","contentUrl":"https:\/\/www.holstein.ch\/wp-content\/uploads\/2023\/09\/holstein_switzerland_logo.png","width":800,"height":621,"caption":"Holstein Switzerland"},"image":{"@id":"https:\/\/www.holstein.ch\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/HolSwi","https:\/\/www.youtube.com\/@holsteinswitzerland","https:\/\/www.instagram.com\/holstein_switzerland"]},{"@type":"Person","@id":"https:\/\/www.holstein.ch\/de\/#\/schema\/person\/91e83d490a3dfd0906e65d37ecbcbfb6","name":"Marie-Jos\u00e9 Rossier","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/68ae16187ec4e6b8556e0e811e57dcb7c21c138f955e02087102f283ee2b3bb6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/68ae16187ec4e6b8556e0e811e57dcb7c21c138f955e02087102f283ee2b3bb6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/68ae16187ec4e6b8556e0e811e57dcb7c21c138f955e02087102f283ee2b3bb6?s=96&d=mm&r=g","caption":"Marie-Jos\u00e9 Rossier"}}]}},"_links":{"self":[{"href":"https:\/\/www.holstein.ch\/de\/wp-json\/wp\/v2\/posts\/35859","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.holstein.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.holstein.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.holstein.ch\/de\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/www.holstein.ch\/de\/wp-json\/wp\/v2\/comments?post=35859"}],"version-history":[{"count":1,"href":"https:\/\/www.holstein.ch\/de\/wp-json\/wp\/v2\/posts\/35859\/revisions"}],"predecessor-version":[{"id":35860,"href":"https:\/\/www.holstein.ch\/de\/wp-json\/wp\/v2\/posts\/35859\/revisions\/35860"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.holstein.ch\/de\/wp-json\/wp\/v2\/media\/35852"}],"wp:attachment":[{"href":"https:\/\/www.holstein.ch\/de\/wp-json\/wp\/v2\/media?parent=35859"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.holstein.ch\/de\/wp-json\/wp\/v2\/categories?post=35859"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.holstein.ch\/de\/wp-json\/wp\/v2\/tags?post=35859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}